{"id":5830,"date":"2023-12-02T05:12:04","date_gmt":"2023-12-02T05:12:04","guid":{"rendered":"https:\/\/cronicasvinotinto.com\/?p=5830"},"modified":"2024-01-06T22:17:26","modified_gmt":"2024-01-06T22:17:26","slug":"por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego","status":"publish","type":"post","link":"https:\/\/cronicasvinotinto.com\/en\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/","title":{"rendered":"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos &#8211; Informe completo desde su llegada al club griego y vuelta a Colombia"},"content":{"rendered":"<div class=\"croni-antes-del-contenido_2\" id=\"croni-2439008354\"><script data-cfasync=\"false\" type=\"text\/javascript\" id=\"clever-core\"> \/* <![CDATA[ *\/ (function (document, window) { var a, c = document.createElement(\"script\"), f = window.frameElement; c.id = \"CleverCoreLoader83928\"; c.src = \"https:\/\/scripts.cleverwebserver.com\/28d9a805dec9ac74dac45d79386cb81d.js\"; c.async = !0; c.type = \"text\/javascript\"; c.setAttribute(\"data-target\", window.name || (f && f.getAttribute(\"id\"))); c.setAttribute(\"data-callback\", \"put-your-callback-function-here\"); c.setAttribute(\"data-callback-url-click\", \"put-your-click-macro-here\"); c.setAttribute(\"data-callback-url-view\", \"put-your-view-macro-here\"); try { a = parent.document.getElementsByTagName(\"script\")[0] || document.getElementsByTagName(\"script\")[0]; } catch (e) { a = !1; } a || (a = document.getElementsByTagName(\"head\")[0] || document.getElementsByTagName(\"body\")[0]); a.parentNode.insertBefore(c, a); })(document, window); \/* ]]> *\/ <\/script><\/div>\n<p class=\"wp-block-paragraph\"><strong>Es un hecho: Joel Graterol volver\u00e1 al Am\u00e9rica de Cali. <\/strong>Sin embargo, todo su periplo en Europa no fue tan positivo. <em>Varias pueden ser las razones, pero en Cr\u00f3nicas Vinotinto lo atribu\u00edmos a la falta de confianza que han tenido los tres directores t\u00e9cnicos que han pasado por el actual club de Graterol, que buscan arqueros experimentados para asegurar la permanencia del Panetoilikos en la Superliga 1 de Grecia.  <\/em><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u00abLlegar a colombia y llegar a la mecha ha sido una bendici\u00f3n de DIOS. Ahora me voy mucho mejor de lo que llegu\u00e9, me voy con una maleta llena de una experiencia magn\u00edfica que adquir\u00ed en estos a\u00f1os que me hicieron crecer mucho y de momentos maravillosos dentro y fuera de la cancha con esta instituci\u00f3n.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed se despidi\u00f3 Joel Graterol, guardameta venezolano, de la afici\u00f3n colombiana desde una publicaci\u00f3n de su cuenta de Instagram antes de partir al <strong>Paneitolikos de Grecia<\/strong> con contrato de a\u00f1o y medio (hasta junio de 2024). <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"263\" height=\"318\" src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/logo-panetolikos-site-33.png.webp\" alt=\"\" class=\"wp-image-5846\" style=\"width:185px;height:auto\" srcset=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/logo-panetolikos-site-33.png.webp 263w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/logo-panetolikos-site-33.png-248x300.webp 248w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/logo-panetolikos-site-33.png-10x12.webp 10w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El Am\u00e9rica de Cali, equipo donde brill\u00f3 y sali\u00f3 campe\u00f3n en 2020, luch\u00f3 por su renovaci\u00f3n pero no pudo retener al portero vinotinto, ya que su meta era dar el salto a Europa para estar m\u00e1s cerca del equipo de sus deseos, el Inter de Mil\u00e1n, y seguir los pasos exitosos del italiano Francesco Toldo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Graterol se uni\u00f3 al equipo que hace vida en Agrinio, una ciudad modesta ubicada en el centro de Grecia, con una poblaci\u00f3n cercana a los 100,000 habitantes: Panetolikos, un club de media tabla que participa en la Superliga 1 de Grecia y que en 2026 celebrar\u00e1 su centenario. Aunque sus largos a\u00f1os de historia, no le han evitado experimentar una crisis de resultados los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Graterol-1024x768.webp\" alt=\"\" class=\"wp-image-5843\" srcset=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Graterol-1024x768.webp 1024w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Graterol-300x225.webp 300w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Graterol-768x576.webp 768w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Graterol-16x12.webp 16w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Graterol-860x645.webp 860w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Graterol.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo dirigido por Yannis Anastasiou, ya en la parte final de la fase regular, buscaba un arquero solvente para sustituir al lesionado portero griego de 32 a\u00f1os, <strong>Giannis Anestis<\/strong>, titular del \u00abcanario\u00bb (como se le conoce al Panetolikos). <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La Superliga 1 de Grecia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para entender un poco el formato y en el momento en el que lleg\u00f3 Joel Graterol al f\u00fatbol griego, explicaremos c\u00f3mo se juega su m\u00e1xima categor\u00eda. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El torneo se llama Stoiximan Super League,&nbsp;o Superliga 1 de Grecia. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Juegan 14 equipos en una fase de todos contra todos en partidos de ida y vuelta. <\/li>\n\n\n\n<li>Los primeros 6 equipos, avanzan a una fase llamada \u00abRonda de campeonato\u00bb o \u00abChampionship Round\u00bb para definir al campe\u00f3n y los puestos de torneos europeos en un todos contra todos.<\/li>\n\n\n\n<li> Los 8 restantes entran en un mini eliminatorio tambi\u00e9n un todos contra todos, pero de una sola ronda, y los dos \u00faltimos de la tabla descienden a la Superliga 2. <\/li>\n\n\n\n<li>Lo curioso de esto, es que siguen acumulando los mismos puntos, no comienza la cuenta desde cero. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Los partidos de Graterol<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-02-a-las-12.08.16\u202fa.m-1024x771.png\" alt=\"\" class=\"wp-image-5849\" srcset=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-02-a-las-12.08.16\u202fa.m-1024x771.png 1024w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-02-a-las-12.08.16\u202fa.m-300x226.png 300w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-02-a-las-12.08.16\u202fa.m-768x578.png 768w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-02-a-las-12.08.16\u202fa.m-1536x1156.png 1536w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-02-a-las-12.08.16\u202fa.m-16x12.png 16w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-02-a-las-12.08.16\u202fa.m-860x647.png 860w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-02-a-las-12.08.16\u202fa.m.png 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">FOTO ALGOMASQUEVINOTINTO<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El DT Anastasiou, que estaba con el Panetolikos desde junio de 2021, aline\u00f3 a Joel Graterol a los 12 d\u00edas de su presentaci\u00f3n. <strong>El venezolano respondi\u00f3 a su titularidad con una buena actuaci\u00f3n<\/strong>, en la victoria 1-0 sobre el Ionikos Nikeas, el 19 de febrero de 2023, en la fecha 23 de 26. El nativo de Valencia, estado Carabobo, hizo tres atajadas y recibi\u00f3 una puntuaci\u00f3n en Sofascore de 7.8, lo que le hizo merecedor del estar en el equipo de la semana de la liga griega en su debut. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su segundo encuentro, correspondiente a la jornada 24 del campeonato griego, Graterol fue nuevamente titular en el partido de visitante contra el Levadiakos. Mantuvo su porter\u00eda imbatida, contribuyendo a un empate sin goles (0-0).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 6 de marzo de 2023, tambi\u00e9n arranc\u00f3 como titular y lo hizo por primera vez, junto a su compatriota Juanpi, en la fecha 25. En ese encuentro, el Panathinaikos derrot\u00f3 2-0 al equipo de Graterol. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fecha 26, el \u00faltimo partido como local en la fase regular, el Panatolikos empat\u00f3 1-1 contra Lamia. Joel Graterol sali\u00f3 al campo en el 11 principal de Anastasiou.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"451\" src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/33864a21-joel_graterol_panetolikos_panathinaikos_2023_onsportsgr_1349x594-1024x451.webp\" alt=\"\" class=\"wp-image-5851\" srcset=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/33864a21-joel_graterol_panetolikos_panathinaikos_2023_onsportsgr_1349x594-1024x451.webp 1024w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/33864a21-joel_graterol_panetolikos_panathinaikos_2023_onsportsgr_1349x594-300x132.webp 300w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/33864a21-joel_graterol_panetolikos_panathinaikos_2023_onsportsgr_1349x594-768x338.webp 768w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/33864a21-joel_graterol_panetolikos_panathinaikos_2023_onsportsgr_1349x594-18x8.webp 18w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/33864a21-joel_graterol_panetolikos_panathinaikos_2023_onsportsgr_1349x594-860x379.webp 860w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/33864a21-joel_graterol_panetolikos_panathinaikos_2023_onsportsgr_1349x594-jpg.webp 1349w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tras esos resultados, el Panetolikos qued\u00f3 s\u00e9ptimo en la tabla de posiciones de la Superliga 1 y no pudo avanzar a la fase de campeonato sino que tuvo que disputar la ronda de \u00abrelegaci\u00f3n\u00bb al obtener 29 puntos de 78. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Se jugaba la permanencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la fase de relegaci\u00f3n, ocho equipos se disputan un partido todos contra todos, en el que solo seis permanecer\u00e1 en la primera divisi\u00f3n.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Graterol fue relegado al banco y el arquero habitual, el experimentado Anestis, volvi\u00f3 a ser titular en esta fase definitoria de la temporada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fecha 1: El 18 de marzo se jug\u00f3 el primer partido frente al Asteras Tripoli. Panetolikos perdi\u00f3 2-1 como visitante y Graterol no fue convocado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los siguientes partidos, Graterol estuvo convocado pero no jug\u00f3 ninguno de ellos. De los siete juegos en disputa, solo 1 termin\u00f3 en empate, todos fueron con derrota del Panetolikos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fecha 2 (1\/04\/23) Panetolikos 1-3 Lamia (Graterol suplente)<br>Fecha 3 (8\/04\/23) Panetolikos 0-1 IONIKOS (Graterol suplente)<br>Fecha 4 (22\/04\/23) PAS GIANNINA 3-2 Panetolikos (Graterol suplente)<br>Fecha 5 (29\/04\/23) Panetolikos 2-2 Levadiakos (Graterol suplente)<br>Fecha 6 (6\/05\/23) Atromitos 2-0 Panetolikos (Graterol suplente)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima fecha de la permanencia se jug\u00f3 el 13 de mayo de 2023 frente al OFI (l\u00edder de esta eliminatoria), ya con el calendario casi definido y el Panetolikos asegur\u00e1ndose casi la permanencia, Joel Graterol sali\u00f3 a la cancha como titular junto con algunos suplentes y su quipo cay\u00f3 0-2. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo del partido estuvo bien cerrado y pudo ser para los dos, pero en el minuto 84, un despeje de un centro rival, se meti\u00f3 en la arquer\u00eda y Graterol no lo pudo sacar.<strong> El guardameta venezolano intent\u00f3 sacarla con los pu\u00f1os pero el bal\u00f3n peg\u00f3 en el palo y se meti\u00f3. En una acci\u00f3n anterior, ya hab\u00eda sacado una parecida pero en esta parece resbalarse. <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/salvvada-1.mp4\"><\/video><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/gol1.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Y el segundo gol, fue una salida en falso que tuvo el venezolano ante un buen centro rival.<\/strong> Esas dos jugadas, pudieron ser determinantes para quitarle la titularidad hasta la actualidad. <\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/gol2.mp4\"><\/video><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Nueva temporada, nuevo t\u00e9cnico<\/strong>, nuevas ca\u00eddas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La crisis de resultados han hecho que la dirigencia del Panetolikos busque alternativas en la direcci\u00f3n t\u00e9cnica para ver si esta temporada pueden tener un buen ritmo. Uno de los que lleg\u00f3 para \u00absalvar\u00bb al equipo canario fue el argentino\/espa\u00f1ol <strong>Gabriel Schurrer.<\/strong> El ex jugador con pasado en Olimpiakos y M\u00e1laga, lleg\u00f3 en julio de 2023 con sus asistentes Juan y Gustavo Zubeld\u00eda para intentar arrancar bien la temporada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en los primeros partidos, seg\u00fan rese\u00f1\u00f3 la prensa en Grecia, el DT argentino experiment\u00f3 en sus sistemas de juego, se vio \u00abconfundido y nunca us\u00f3 un solo sistema\u00bb. <strong>Sea como sea, Joel Graterol no recibi\u00f3 la confianza de Schurrer. Y volvi\u00f3 a quedar relegado en el banco de suplentes en el arranque de la primera divisi\u00f3n griega. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la salida del guardameta Hay que a\u00f1adir que con el nuevo t\u00e9cnico, lleg\u00f3 un nuevo competidor para Graterol: el guardameta griego <strong>Stefano Kapino<\/strong>, selecci\u00f3n nacional de Grecia en varios partidos del 2021 y quien r\u00e1pidamente se adjudic\u00f3 la titularidad del Panetolikos, quiz\u00e1s por su basta experiencia en la liga nacional de su pa\u00eds.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero el Panetolikos no levant\u00f3 y en<strong> seis partidos al mando del t\u00e9cnico argentino<\/strong>, s\u00f3lo obtuvo tres puntos, producto de tres empates y tres derrotas. En todos esos encuentros, Graterol estuvo de suplente, excepto uno, que no fue convocado (la cuarta fecha). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para revertir situaci\u00f3n de resultados negativos de un Panetolikos que se hund\u00eda en la tabla de la Superliga 1 de Grecia, la dirigencia trajo al griego <strong>Giannis Petrakis<\/strong> en octubre de 2023. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-01-a-las-11.59.00\u202fp.m-1-1024x577.png\" alt=\"\" class=\"wp-image-5845\" style=\"width:383px;height:auto\" srcset=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-01-a-las-11.59.00\u202fp.m-1-1024x577.png 1024w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-01-a-las-11.59.00\u202fp.m-1-300x169.png 300w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-01-a-las-11.59.00\u202fp.m-1-768x432.png 768w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-01-a-las-11.59.00\u202fp.m-1-18x10.png 18w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-01-a-las-11.59.00\u202fp.m-1-860x484.png 860w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/Captura-de-pantalla-2023-12-01-a-las-11.59.00\u202fp.m-1.png 1442w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Desde que lleg\u00f3 Petrakis no le ha dado chance a Graterol de reivindicarse.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">A su llegada, el Panetolikos venci\u00f3 2-0 al VOLOS NFC, en la octava fecha (Graterol no fue convocado). De ah\u00ed en adelante, han sido cuatro derrotas al hilo. Graterol fue suplente en tres de ellas y en la \u00faltima jornada hasta el momento de esta publicaci\u00f3n (la 12) no fue convocado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la Copa de Grecia, Graterol tampoco fue tomado en cuenta por Petrakis. El DT griego se decant\u00f3 por el tercer guardametas, Antonis Stergiakis, quien defendi\u00f3 el arco del Panetolikos en el empate ante el Diagoras 1-1 y se alarg\u00f3 a los penales. El equipo \u00abcanario\u00bb avanz\u00f3 a las fases finales del torneo. Este partido tuvo desarrollo el 11 de octubre de 2023. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Convocatorias vinotinto<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"770\" src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/graterol-1024x770.png\" alt=\"\" class=\"wp-image-5842\" srcset=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/graterol-1024x770.png 1024w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/graterol-300x226.png 300w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/graterol-768x577.png 768w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/graterol-16x12.png 16w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/graterol-860x646.png 860w, https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/graterol.png 1192w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">FOTO ARCHIVO JOEL GRATEROL<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El consuelo que ha tenido Graterol despu\u00e9s irse a Europa, ha sido los constantes llamados que ha recibido de la Selecci\u00f3n Nacional de F\u00fatbol de Venezuela, la Vinotinto y su Director T\u00e9cnico, Fernando \u00abBocha\u00bb Batista. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Graterol fue convocado para los partidos amistosos de Venezuela frente a Uzbekistan, el 28 de marzo de 2023 (empate 1-1) y en la fecha FIFA de junio, en los que la Vinotinto se midi\u00f3 a Honduras y Guatemala en Estados Unidos. En los tres partidos, Graterol fue titular ante Honduras y suplente ante Guatemala, ambos terminaron en victoria para Venezuela 1-0.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n Graterol ha sido un fijo en las convocatorias del \u00abBocha\u00bb en las Eliminatorias Sudamericanas, con un total de seis de seis, aunque no ha disputado ning\u00fan minuto, pues la arquer\u00eda titular la tiene su compa\u00f1ero Rafael Romo, de gran momento en Ecuador. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfDebe esperar su chance o regresar a Colombia?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien es cierto, volver a donde se estaba no es fracasar, Graterol no ha cumplido de lleno su deseo de jugar en Europa. Ante su situaci\u00f3n, de ser suplente en un equipo irregular, varios periodistas han estado especulando sobre el regreso de <strong>Joel Graterol<\/strong> al f\u00fatbol colombiano. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00e9sar Luis Merlo,<\/strong> periodista especializado en mercado de pases asegur\u00f3 que \u00ab<em>tiene muchas chances de marcharse del Panetolikos. El club (Panetolikos) tom\u00f3 la decisi\u00f3n de no tenerlo en cuenta y la intenci\u00f3n es que se marche para liberar un cupo<\/em>\u00ab. Por su parte, <strong>Felipe \u00abPipe\u00bb Sierra<\/strong>, periodista deportivo de Win Sports TV (Colombia) a\u00f1ade que \u00ab<em>hay dos equipos interesados en sus servicios y ya conocen las condiciones para poder contratarlo<\/em>\u00ab. Probablemente sea Atl\u00e9tico Nacional o el mismo Am\u00e9rica de Cali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Graterol sigue siendo convocado, la liga de Grecia, que hasta el momento de la publicaci\u00f3n de este art\u00edculo va por la fecha 13, el Panetolikos es \u00faltimo con seis unidades. Si debe irse o quedarse, lo mejor para el jugador, debe decidirlo \u00e9l y sus agentes. Lo mejor para Venezuela ser\u00eda estar en un sitio donde se sienta feliz, agusto con su f\u00fatbol y con ritmo, por supuesto. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vuelta a Cali<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Actualizaci\u00f3n 5 de enero de 2024: <strong>Joel Graterol volver\u00e1 a vestir la camiseta del Am\u00e9rica de Cali en 2024. <\/strong> Con este video publicado en redes sociales, el club colombiano oficializ\u00f3 la vuelta del guardameta venezolano a Colombia: <\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1350\" style=\"aspect-ratio: 1080 \/ 1350;\" width=\"1080\" controls src=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2024\/01\/Snapinsta.app_video_10000000_205337309315141_7501873781344636672_n.mp4\"><\/video><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ficha: Joel Graterol<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nombre completo: Joel David Graterol Nader<\/li>\n\n\n\n<li>Fecha de nacimiento: 13 de febrero de 1997 (26 a\u00f1os)<\/li>\n\n\n\n<li>Lugar de nacimiento: Valencia, Venezuela.&nbsp;<\/li>\n\n\n\n<li>Estatura: 1,82 m.&nbsp;<\/li>\n\n\n\n<li>Posici\u00f3n: Portero.<\/li>\n\n\n\n<li>Equipos: Carabobo, Zamora, Am\u00e9rica de Cali y Panetolikos. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Enlaces consultados: <\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>https:\/\/titormosnet.gr\/ston-panaitoliko-o-zoel-gkraterol\/<\/li>\n\n\n\n<li>https:\/\/www.agrinionews.gr\/se-krisi-o-panaitolikos-se-deini-thesi-o-soyrer\/<\/li>\n\n\n\n<li>https:\/\/www.ole.com.ar\/futbol-internacional\/schurrer-grecia-panetolikos-almeyda-aek_0_uEBXOtBze3.html<\/li>\n\n\n\n<li>https:\/\/www.antena2.com\/futbol\/joel-graterol-fue-confirmado-por-su-nuevo-equipo-sera-rival-de-james-en-grecia<\/li>\n\n\n\n<li>https:\/\/agriniara.gr\/termatofylakas-sponta-zoel-gkraterol-panaitolikou\/<\/li>\n\n\n\n<li>https:\/\/www.sofascore.com\/es\/equipo\/futbol\/panetolikos\/7004<\/li>\n\n\n\n<li>https:\/\/us.soccerway.com\/national\/greece\/super-league\/20232024\/regular-season\/r75615\/<\/li>\n\n\n\n<li>https:\/\/www.panetolikos.gr\/apostoli-agona-me-kifisia\/<\/li>\n\n\n\n<li>https:\/\/www.sportal.gr\/podosfairo\/article\/panaitolikos-ofh-0-2-kynikoi-oi-krhtikoi-termatisan-prwtoi-sta-playouts-2023051315571237455<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Es un hecho: Joel Graterol volver\u00e1 al Am\u00e9rica de Cali. Sin embargo, todo su periplo en Europa no fue tan positivo. Varias pueden ser las razones, pero en Cr\u00f3nicas Vinotinto lo atribu\u00edmos a la falta de confianza que han tenido los tres directores t\u00e9cnicos que han pasado por el actual club de Graterol, que buscan [&hellip;]<\/p>","protected":false},"author":2,"featured_media":5848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1,200],"tags":[263,262,260,261,264,69],"ppma_author":[288],"class_list":["post-5830","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cronicas","category-vinotintos","tag-clubes","tag-grecia","tag-joel-graterol","tag-panetolikos","tag-venezolanos","tag-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos - Informe completo desde su llegada al club griego y vuelta a Colombia - Cr\u00f3nicas Vinotinto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cronicasvinotinto.com\/en\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos - Informe completo desde su llegada al club griego y vuelta a Colombia - Cr\u00f3nicas Vinotinto\" \/>\n<meta property=\"og:description\" content=\"Es un hecho: Joel Graterol volver\u00e1 al Am\u00e9rica de Cali. Sin embargo, todo su periplo en Europa no fue tan positivo. Varias pueden ser las razones, pero en Cr\u00f3nicas Vinotinto lo atribu\u00edmos a la falta de confianza que han tenido los tres directores t\u00e9cnicos que han pasado por el actual club de Graterol, que buscan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cronicasvinotinto.com\/en\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/\" \/>\n<meta property=\"og:site_name\" content=\"Cr\u00f3nicas Vinotinto\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-02T05:12:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-06T22:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1188\" \/>\n\t<meta property=\"og:image:height\" content=\"898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Oliver Gonzalez Leon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oliverggl\" \/>\n<meta name=\"twitter:site\" content=\"@cronicasvinotin\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oliver Gonzalez Leon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/\"},\"author\":{\"name\":\"Oliver Gonzalez Leon\",\"@id\":\"https:\/\/cronicasvinotinto.com\/#\/schema\/person\/e1ba8e862ebb3cc79bef1a8d07752a3d\"},\"headline\":\"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos &#8211; Informe completo desde su llegada al club griego y vuelta a Colombia\",\"datePublished\":\"2023-12-02T05:12:04+00:00\",\"dateModified\":\"2024-01-06T22:17:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/\"},\"wordCount\":1916,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png\",\"keywords\":[\"clubes\",\"Grecia\",\"Joel Graterol\",\"Panetolikos\",\"venezolanos\",\"venezuela\"],\"articleSection\":[\"Cr\u00f3nicas\",\"Vinotintos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/\",\"url\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/\",\"name\":\"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos - Informe completo desde su llegada al club griego y vuelta a Colombia - Cr\u00f3nicas Vinotinto\",\"isPartOf\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png\",\"datePublished\":\"2023-12-02T05:12:04+00:00\",\"dateModified\":\"2024-01-06T22:17:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#primaryimage\",\"url\":\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png\",\"contentUrl\":\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png\",\"width\":1188,\"height\":898},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cronicasvinotinto.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos &#8211; Informe completo desde su llegada al club griego y vuelta a Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cronicasvinotinto.com\/#website\",\"url\":\"https:\/\/cronicasvinotinto.com\/\",\"name\":\"Cr\u00f3nicas Vinotinto\",\"description\":\"Noticias, historias, opini\u00f3n y pasi\u00f3n por la Vinotinto en su camino hacia el Mundial.\",\"publisher\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cronicasvinotinto.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cronicasvinotinto.com\/#organization\",\"name\":\"Cr\u00f3nicas Vinotinto\",\"url\":\"https:\/\/cronicasvinotinto.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cronicasvinotinto.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/09\/cronicasvinotinto_logo_dia-1.png\",\"contentUrl\":\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/09\/cronicasvinotinto_logo_dia-1.png\",\"width\":601,\"height\":197,\"caption\":\"Cr\u00f3nicas Vinotinto\"},\"image\":{\"@id\":\"https:\/\/cronicasvinotinto.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/cronicasvinotin\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cronicasvinotinto.com\/#\/schema\/person\/e1ba8e862ebb3cc79bef1a8d07752a3d\",\"name\":\"Oliver Gonzalez Leon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cronicasvinotinto.com\/#\/schema\/person\/image\/ccddb9c71b1dfe90392f95cd6eee49a2\",\"url\":\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2024\/01\/1701879400854-jpeg.webp\",\"contentUrl\":\"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2024\/01\/1701879400854-jpeg.webp\",\"caption\":\"Oliver Gonzalez Leon\"},\"description\":\"Periodista deportivo venezolano, cuenta con m\u00e1s de 12 a\u00f1os de experiencia en medios de comunicaci\u00f3n impresos y digitales. Domina el \u00e1rea multimedia, pero tambi\u00e9n ha trabajado como periodista deportivo en medios locales y nacionales en Venezuela y Per\u00fa. Actualmente reside en EEUU, desde donde dirige Cr\u00f3nicas Vinotinto.\",\"sameAs\":[\"https:\/\/x.com\/oliverggl\"],\"url\":\"https:\/\/cronicasvinotinto.com\/en\/author\/ogonzalez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos - Informe completo desde su llegada al club griego y vuelta a Colombia - Cr\u00f3nicas Vinotinto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cronicasvinotinto.com\/en\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/","og_locale":"en_US","og_type":"article","og_title":"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos - Informe completo desde su llegada al club griego y vuelta a Colombia - Cr\u00f3nicas Vinotinto","og_description":"Es un hecho: Joel Graterol volver\u00e1 al Am\u00e9rica de Cali. Sin embargo, todo su periplo en Europa no fue tan positivo. Varias pueden ser las razones, pero en Cr\u00f3nicas Vinotinto lo atribu\u00edmos a la falta de confianza que han tenido los tres directores t\u00e9cnicos que han pasado por el actual club de Graterol, que buscan [&hellip;]","og_url":"https:\/\/cronicasvinotinto.com\/en\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/","og_site_name":"Cr\u00f3nicas Vinotinto","article_published_time":"2023-12-02T05:12:04+00:00","article_modified_time":"2024-01-06T22:17:26+00:00","og_image":[{"width":1188,"height":898,"url":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png","type":"image\/png"}],"author":"Oliver Gonzalez Leon","twitter_card":"summary_large_image","twitter_creator":"@oliverggl","twitter_site":"@cronicasvinotin","twitter_misc":{"Written by":"Oliver Gonzalez Leon","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#article","isPartOf":{"@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/"},"author":{"name":"Oliver Gonzalez Leon","@id":"https:\/\/cronicasvinotinto.com\/#\/schema\/person\/e1ba8e862ebb3cc79bef1a8d07752a3d"},"headline":"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos &#8211; Informe completo desde su llegada al club griego y vuelta a Colombia","datePublished":"2023-12-02T05:12:04+00:00","dateModified":"2024-01-06T22:17:26+00:00","mainEntityOfPage":{"@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/"},"wordCount":1916,"commentCount":0,"publisher":{"@id":"https:\/\/cronicasvinotinto.com\/#organization"},"image":{"@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#primaryimage"},"thumbnailUrl":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png","keywords":["clubes","Grecia","Joel Graterol","Panetolikos","venezolanos","venezuela"],"articleSection":["Cr\u00f3nicas","Vinotintos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/","url":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/","name":"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos - Informe completo desde su llegada al club griego y vuelta a Colombia - Cr\u00f3nicas Vinotinto","isPartOf":{"@id":"https:\/\/cronicasvinotinto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#primaryimage"},"image":{"@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#primaryimage"},"thumbnailUrl":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png","datePublished":"2023-12-02T05:12:04+00:00","dateModified":"2024-01-06T22:17:26+00:00","breadcrumb":{"@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#primaryimage","url":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png","contentUrl":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/12\/joelgraterol.png","width":1188,"height":898},{"@type":"BreadcrumbList","@id":"https:\/\/cronicasvinotinto.com\/por-que-joel-graterol-no-juega-con-el-panetolikos-informe-completo-de-su-llegada-al-club-griego\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cronicasvinotinto.com\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 Joel Graterol no jugaba con el Panetolikos &#8211; Informe completo desde su llegada al club griego y vuelta a Colombia"}]},{"@type":"WebSite","@id":"https:\/\/cronicasvinotinto.com\/#website","url":"https:\/\/cronicasvinotinto.com\/","name":"Cr\u00f3nicas Vinotinto","description":"Noticias, historias, opini\u00f3n y pasi\u00f3n por la Vinotinto en su camino hacia el Mundial.","publisher":{"@id":"https:\/\/cronicasvinotinto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cronicasvinotinto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cronicasvinotinto.com\/#organization","name":"Cr\u00f3nicas Vinotinto","url":"https:\/\/cronicasvinotinto.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cronicasvinotinto.com\/#\/schema\/logo\/image\/","url":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/09\/cronicasvinotinto_logo_dia-1.png","contentUrl":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2023\/09\/cronicasvinotinto_logo_dia-1.png","width":601,"height":197,"caption":"Cr\u00f3nicas Vinotinto"},"image":{"@id":"https:\/\/cronicasvinotinto.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/cronicasvinotin"]},{"@type":"Person","@id":"https:\/\/cronicasvinotinto.com\/#\/schema\/person\/e1ba8e862ebb3cc79bef1a8d07752a3d","name":"Oliver Gonzalez Leon","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cronicasvinotinto.com\/#\/schema\/person\/image\/ccddb9c71b1dfe90392f95cd6eee49a2","url":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2024\/01\/1701879400854-jpeg.webp","contentUrl":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2024\/01\/1701879400854-jpeg.webp","caption":"Oliver Gonzalez Leon"},"description":"Periodista deportivo venezolano, cuenta con m\u00e1s de 12 a\u00f1os de experiencia en medios de comunicaci\u00f3n impresos y digitales. Domina el \u00e1rea multimedia, pero tambi\u00e9n ha trabajado como periodista deportivo en medios locales y nacionales en Venezuela y Per\u00fa. Actualmente reside en EEUU, desde donde dirige Cr\u00f3nicas Vinotinto.","sameAs":["https:\/\/x.com\/oliverggl"],"url":"https:\/\/cronicasvinotinto.com\/en\/author\/ogonzalez\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"ogonzalez","display_name":"Oliver Gonzalez Leon","avatar_url":{"url":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2024\/01\/1701879400854-jpeg.webp","url2x":"https:\/\/cronicasvinotinto.com\/wp-content\/uploads\/2024\/01\/1701879400854-jpeg.webp"},"author_category":"","user_url":"","last_name":"Gonzalez Leon","first_name":"Oliver","job_title":"","description":"Periodista deportivo venezolano, cuenta con m\u00e1s de 12 a\u00f1os de experiencia en medios de comunicaci\u00f3n impresos y digitales. Domina el \u00e1rea multimedia, pero tambi\u00e9n ha trabajado como periodista deportivo en medios locales y nacionales en Venezuela y Per\u00fa. Actualmente reside en EEUU donde dirige Cr\u00f3nicas Vinotinto."}],"_links":{"self":[{"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/posts\/5830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/comments?post=5830"}],"version-history":[{"count":13,"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/posts\/5830\/revisions"}],"predecessor-version":[{"id":5978,"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/posts\/5830\/revisions\/5978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/media\/5848"}],"wp:attachment":[{"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/media?parent=5830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/categories?post=5830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/tags?post=5830"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/cronicasvinotinto.com\/en\/wp-json\/wp\/v2\/ppma_author?post=5830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}